{"id":44709,"date":"2020-11-20T16:45:59","date_gmt":"2020-11-20T15:45:59","guid":{"rendered":"https:\/\/www.sestogrado.it\/?post_type=product&#038;p=44709"},"modified":"2026-04-16T10:01:42","modified_gmt":"2026-04-16T08:01:42","slug":"ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma","status":"publish","type":"product","link":"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/","title":{"rendered":"Ferrino Lightec 1200 Duvet rds down saccoletto in piuma"},"content":{"rendered":"<p>Il Ferrino Lightec 1200 Duvet RDS Down \u00e8 un saccoletto in piuma ad elevatissima termicit\u00e0, adatto agli utilizzatori pi\u00f9 esigenti, a chi richiede il massimo delle prestazioni per alpinismo o trekking multistagionale, con un comfort termico intorno ai -8\u00b0C.<\/p>\n<ul>\n<li>Comfort termico intorno ai \u20118\u00b0C<\/li>\n<li>Dispersione del calore minima, grazie alle cuciture sfalsate<\/li>\n<li>Apertura facilitata con sistema &#8220;one touch&#8221;<\/li>\n<li>Forma 3D nella zona piedi per un maggiore comfort<\/li>\n<li>Lampo a &#8220;2 vie&#8221; laterali e lampo nella zona piedi permette di aprire il fondo del saccoletto, regolando la temperatura interna<\/li>\n<li>Cupolino parafreddo<\/li>\n<li>Coprilampo barriera interna imbottita lungo la lampo per evitare l\u2019ingresso del freddo<\/li>\n<li>Taschina interna<\/li>\n<li>Sacca di compressione inclusa permette di ridurre il volume del saccoletto per un inserimento facilitato nello zaino<\/li>\n<li>Tessuto esterno: 100% Nylon 390T 20D<\/li>\n<li>Tessuto interno:\u00a0100% Nylon 390T 20D<\/li>\n<li>Imbottitura: Lightec 1200: 650g down 80\/20 550 cuin<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Dalle elevatissime capacit\u00e0 termiche, il Ferrino Lightec 1200 Duvet rds down \u00e8 un saccoletto in piuma adatto a bivacchi, alpinismo, spedizioni multi stagione.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>COSA C\u2019E\u2019 DA SAPERE NELLA SCELTA DI UN SACCOLETTO<\/strong><\/h4>\n<ul>\n<li><strong>Temperatura massima di comfort\u00a0<\/strong>\u00e8 data dalla massima temperatura che consente di dormire ad un uomo standard senza sudare abbondantemente.<br \/>\n\u00c8 determinata con le cerniere del sacco a pelo aperto, le braccia al di fuori ed il cappuccio aperto.<\/li>\n<li><strong>Temperatura di comfort<\/strong>\u00a0\u00e8 il valore di temperatura (riferito ad una donna standard) che riesce ad effettuare una notte intera di sonno in posizione rilassata.<\/li>\n<\/ul>\n<ul>\n<li><strong>Limite inferiore di comfort\u00a0<\/strong>definisce la temperatura minima (riferita ad un uomo standard) cui \u00e8 possibile dormire in posizione rannicchiata per otto ore senza svegliarsi.<\/li>\n<\/ul>\n<ul>\n<li><strong>Temperatura estrema\u00a0<\/strong>\u00e8 la temperatura minima a cui il saccoletto protegge l\u2019utilizzatore (donna standard) dalla ipotermia. Permette di effettuare sei ore di sonno scomodo senza che la temperatura interna scenda a livello di pericolo.<\/li>\n<\/ul>\n<p>Nella scelta del vostro saccoletto vi raccomandiamo di tener conto delle temperature di comfort e intermedie anche in funzione del vostro\u00a0livello di preparazione atletica.<\/p>\n<p>Le sensazioni di caldo e freddo sono dovute al fatto che il nostro corpo sta producendo maggiore o minore quantit\u00e0 di calore rispetto a quella che stiamo perdendo a vantaggio dell\u2019ambiente circostante.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>PRINCIPALI FATTORI FISIOLOGICI CHE INFLUENZANO LA SENSAZIONE DI CALDO \/ FREDDO<\/strong><\/h4>\n<ul>\n<li><strong>Metabolismo:\u00a0<\/strong>dormendo una persona genera 75\/100 Watts di calore, in funzione di diversi fattori quali l\u2019et\u00e0, il sesso, il peso, l\u2019abitudine e le condizioni psicofisiche.<\/li>\n<li><strong>Peso:<\/strong>\u00a0una persona in sovrappeso \u00e8 solita avere un metabolismo pi\u00f9 lento.<br \/>\nIn genere mangia pi\u00f9 di quanto consumi.<br \/>\nQuando intraprendiamo un\u2019impresa alpinistica spesso assumiamo meno calorie di quante se ne consumino.<br \/>\nLe persone in sovrappeso saranno in grado di attingere energia dalle loro riserve grasse e inoltre dispongono di un isolamento naturale superiore alle persone magre.<\/li>\n<li><strong>Et\u00e0:<\/strong>\u00a0il metabolismo \u00e8 collegato all\u2019et\u00e0. Una persona anziana genera meno calore e pertanto avverte il freddo prima di una persona giovane.<\/li>\n<li><strong>Sesso:<\/strong>\u00a0le donne sentono il freddo in genere pi\u00f9 degli uomini tanto che il valore standard di comfort per la donna \u00e8 di 5\u00b0C pi\u00f9 elevato di quello dell\u2019uomo.<\/li>\n<li><strong>Abitudine:<\/strong>\u00a0buona parte degli abitanti del mondo occidentale vive in case dotate di riscaldamento centralizzato, lavora in uffici con l\u2019aria condizionata e si sposta solo all\u2019interno di autovetture climatizzate. Questo stile di vita riduce l\u2019abitudine del corpo alla sopportazione del freddo.<\/li>\n<li><strong>Esperienza:<\/strong>\u00a0l\u2019esperienza e la familiarit\u00e0 con l\u2019attrezzatura con cui si dormir\u00e0 all\u2019aperto aiutano ad ottenere da queste le massime prestazioni. Un principiante avvertir\u00e0 generalmente un maggiore disagio e pi\u00f9 freddo di una persona esperta.<\/li>\n<li><strong>Forma Fisica:<\/strong>\u00a0se conduciamo una vita sedentaria e ci sottoponiamo ad una escursione faticosa avvertiremo subito la fatica. La spossatezza riduce la produzione di calore e questo comporta sensazione di freddo.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>1870 Tutto inizia in un negozio di vernici, a Torino. Cesare Ferrino ha un\u2019intuizione rivoluzionaria: impermeabilizzare i tessuti. Il successo \u00e8 immediato, in tutta italia. Dal tessuto alla manifattura le prime tende in dotazione a esploratori e alpinisti, poi gli anni dell\u2019alpinismo leggendario, nel 1994 l&#8217;installazione sul Monte Rosa a 3585 del HighLab, un laboratorio permanente in alta quota nel\u00a0rifugio Quintino Sella, per le prove di nuovi materiali e prototipi. Ferrino \u00e8 un punto di riferimento per le grandi avventure outdoor, nel 1870 come oggi.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Il Ferrino Lightec 1200 Duvet RDS Down \u00e8 un saccoletto in piuma ad elevatissima termicit\u00e0, adatto agli utilizzatori pi\u00f9 esigenti, [&hellip;]<\/p>\n","protected":false},"featured_media":112786,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[614],"product_cat":[577],"product_tag":[],"class_list":{"0":"post-44709","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-ferrino","7":"product_cat-sacchi-a-pelo","9":"first","10":"instock","11":"sale","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ferrino Lightec 1200 Duvet rds down saccoletto in piuma - Sestogrado<\/title>\n<meta name=\"description\" content=\"Il Ferrino Lightec 1200 Duvet RDS Down \u00e8 un saccoletto in piuma ad elevatissima termicit\u00e0, adatto agli utilizzatori pi\u00f9 esigenti, a chi richiede il massimo delle prestazioni per alpinismo o trekking multistagionale, con un comfort termico intorno ai -8\u00b0C. Dalle elevatissime capacit\u00e0 termiche, il Ferrino Lightec 1200 Duvet rds down \u00e8 un saccoletto in piuma adatto a bivacchi, alpinismo, spedizioni multi stagione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferrino Lightec 1200 Duvet rds down saccoletto in piuma - Sestogrado\" \/>\n<meta property=\"og:description\" content=\"Il Ferrino Lightec 1200 Duvet RDS Down \u00e8 un saccoletto in piuma ad elevatissima termicit\u00e0, adatto agli utilizzatori pi\u00f9 esigenti, a chi richiede il massimo delle prestazioni per alpinismo o trekking multistagionale, con un comfort termico intorno ai -8\u00b0C. Dalle elevatissime capacit\u00e0 termiche, il Ferrino Lightec 1200 Duvet rds down \u00e8 un saccoletto in piuma adatto a bivacchi, alpinismo, spedizioni multi stagione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/\" \/>\n<meta property=\"og:site_name\" content=\"Sestogrado\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Sestogrado\/1542635979353017?ref=bookmarks\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T08:01:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sestogrado.it\/wp-content\/uploads\/2020\/11\/09-1200.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Prezzo\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;&nbsp;286,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/\",\"url\":\"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/\",\"name\":\"Ferrino Lightec 1200 Duvet rds down saccoletto in piuma - Sestogrado\",\"isPartOf\":{\"@id\":\"https:\/\/www.sestogrado.it\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sestogrado.it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sestogrado.it\/wp-content\/uploads\/2020\/11\/09-1200.jpg\",\"datePublished\":\"2020-11-20T15:45:59+00:00\",\"dateModified\":\"2026-04-16T08:01:42+00:00\",\"description\":\"Il Ferrino Lightec 1200 Duvet RDS Down \u00e8 un saccoletto in piuma ad elevatissima termicit\u00e0, adatto agli utilizzatori pi\u00f9 esigenti, a chi richiede il massimo delle prestazioni per alpinismo o trekking multistagionale, con un comfort termico intorno ai -8\u00b0C. Dalle elevatissime capacit\u00e0 termiche, il Ferrino Lightec 1200 Duvet rds down \u00e8 un saccoletto in piuma adatto a bivacchi, alpinismo, spedizioni multi stagione.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/#primaryimage\",\"url\":\"https:\/\/www.sestogrado.it\/wp-content\/uploads\/2020\/11\/09-1200.jpg\",\"contentUrl\":\"https:\/\/www.sestogrado.it\/wp-content\/uploads\/2020\/11\/09-1200.jpg\",\"width\":1600,\"height\":1600,\"caption\":\"duvet 1200 giallo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sestogrado.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.sestogrado.it\/it\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ferrino Lightec 1200 Duvet rds down saccoletto in piuma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sestogrado.it\/it\/#website\",\"url\":\"https:\/\/www.sestogrado.it\/it\/\",\"name\":\"Sestogrado\",\"description\":\"yes we climb\",\"publisher\":{\"@id\":\"https:\/\/www.sestogrado.it\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sestogrado.it\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sestogrado.it\/it\/#organization\",\"name\":\"Sestogrado\",\"url\":\"https:\/\/www.sestogrado.it\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.sestogrado.it\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sestogrado.it\/wp-content\/uploads\/2015\/03\/sestogrado-favicon.png\",\"contentUrl\":\"https:\/\/www.sestogrado.it\/wp-content\/uploads\/2015\/03\/sestogrado-favicon.png\",\"width\":260,\"height\":260,\"caption\":\"Sestogrado\"},\"image\":{\"@id\":\"https:\/\/www.sestogrado.it\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pages\/Sestogrado\/1542635979353017?ref=bookmarks\",\"https:\/\/www.youtube.com\/channel\/UC847kAfTkaJsWpc1jtQwr3Q\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\/\/www.sestogrado.it\/it\/termini-e-condizioni\/\"}}]}<\/script>\n<meta property=\"product:brand\" content=\"Ferrino\" \/>\n<meta property=\"product:price:amount\" content=\"286.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferrino Lightec 1200 Duvet rds down saccoletto in piuma - Sestogrado","description":"Il Ferrino Lightec 1200 Duvet RDS Down \u00e8 un saccoletto in piuma ad elevatissima termicit\u00e0, adatto agli utilizzatori pi\u00f9 esigenti, a chi richiede il massimo delle prestazioni per alpinismo o trekking multistagionale, con un comfort termico intorno ai -8\u00b0C. Dalle elevatissime capacit\u00e0 termiche, il Ferrino Lightec 1200 Duvet rds down \u00e8 un saccoletto in piuma adatto a bivacchi, alpinismo, spedizioni multi stagione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/","og_locale":"it_IT","og_type":"article","og_title":"Ferrino Lightec 1200 Duvet rds down saccoletto in piuma - Sestogrado","og_description":"Il Ferrino Lightec 1200 Duvet RDS Down \u00e8 un saccoletto in piuma ad elevatissima termicit\u00e0, adatto agli utilizzatori pi\u00f9 esigenti, a chi richiede il massimo delle prestazioni per alpinismo o trekking multistagionale, con un comfort termico intorno ai -8\u00b0C. Dalle elevatissime capacit\u00e0 termiche, il Ferrino Lightec 1200 Duvet rds down \u00e8 un saccoletto in piuma adatto a bivacchi, alpinismo, spedizioni multi stagione.","og_url":"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/","og_site_name":"Sestogrado","article_publisher":"https:\/\/www.facebook.com\/pages\/Sestogrado\/1542635979353017?ref=bookmarks","article_modified_time":"2026-04-16T08:01:42+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/www.sestogrado.it\/wp-content\/uploads\/2020\/11\/09-1200.jpg","type":"image\/jpeg"}],"twitter_misc":{"Prezzo":"&euro;&nbsp;286,90","Disponibilit\u00e0":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/","url":"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/","name":"Ferrino Lightec 1200 Duvet rds down saccoletto in piuma - Sestogrado","isPartOf":{"@id":"https:\/\/www.sestogrado.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/#primaryimage"},"image":{"@id":"https:\/\/www.sestogrado.it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sestogrado.it\/wp-content\/uploads\/2020\/11\/09-1200.jpg","datePublished":"2020-11-20T15:45:59+00:00","dateModified":"2026-04-16T08:01:42+00:00","description":"Il Ferrino Lightec 1200 Duvet RDS Down \u00e8 un saccoletto in piuma ad elevatissima termicit\u00e0, adatto agli utilizzatori pi\u00f9 esigenti, a chi richiede il massimo delle prestazioni per alpinismo o trekking multistagionale, con un comfort termico intorno ai -8\u00b0C. Dalle elevatissime capacit\u00e0 termiche, il Ferrino Lightec 1200 Duvet rds down \u00e8 un saccoletto in piuma adatto a bivacchi, alpinismo, spedizioni multi stagione.","breadcrumb":{"@id":"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/"]]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/#primaryimage","url":"https:\/\/www.sestogrado.it\/wp-content\/uploads\/2020\/11\/09-1200.jpg","contentUrl":"https:\/\/www.sestogrado.it\/wp-content\/uploads\/2020\/11\/09-1200.jpg","width":1600,"height":1600,"caption":"duvet 1200 giallo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sestogrado.it\/it\/prodotto\/ferrino-lightec-1200-duvet-rds-down-saccoletto-in-piuma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sestogrado.it\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.sestogrado.it\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Ferrino Lightec 1200 Duvet rds down saccoletto in piuma"}]},{"@type":"WebSite","@id":"https:\/\/www.sestogrado.it\/it\/#website","url":"https:\/\/www.sestogrado.it\/it\/","name":"Sestogrado","description":"yes we climb","publisher":{"@id":"https:\/\/www.sestogrado.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sestogrado.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.sestogrado.it\/it\/#organization","name":"Sestogrado","url":"https:\/\/www.sestogrado.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.sestogrado.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.sestogrado.it\/wp-content\/uploads\/2015\/03\/sestogrado-favicon.png","contentUrl":"https:\/\/www.sestogrado.it\/wp-content\/uploads\/2015\/03\/sestogrado-favicon.png","width":260,"height":260,"caption":"Sestogrado"},"image":{"@id":"https:\/\/www.sestogrado.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Sestogrado\/1542635979353017?ref=bookmarks","https:\/\/www.youtube.com\/channel\/UC847kAfTkaJsWpc1jtQwr3Q"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/www.sestogrado.it\/it\/termini-e-condizioni\/"}}]},"product_brand":"Ferrino","product_price_amount":"286.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.sestogrado.it\/it\/wp-json\/wp\/v2\/product\/44709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sestogrado.it\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sestogrado.it\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sestogrado.it\/it\/wp-json\/wp\/v2\/comments?post=44709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sestogrado.it\/it\/wp-json\/wp\/v2\/media\/112786"}],"wp:attachment":[{"href":"https:\/\/www.sestogrado.it\/it\/wp-json\/wp\/v2\/media?parent=44709"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.sestogrado.it\/it\/wp-json\/wp\/v2\/product_brand?post=44709"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sestogrado.it\/it\/wp-json\/wp\/v2\/product_cat?post=44709"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sestogrado.it\/it\/wp-json\/wp\/v2\/product_tag?post=44709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}